{"id":60553,"date":"2025-11-24T10:42:39","date_gmt":"2025-11-24T10:42:39","guid":{"rendered":"https:\/\/pasaportealasalud.com\/testimonios\/"},"modified":"2026-07-23T12:55:32","modified_gmt":"2026-07-23T12:55:32","slug":"testimonios","status":"publish","type":"page","link":"https:\/\/pasaportealasalud.com\/es\/testimonios\/","title":{"rendered":"Testimonios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"60553\" class=\"elementor elementor-60553 elementor-59053\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f9883b elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"2f9883b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9f0329 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a9f0329\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fd2141 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"8fd2141\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7a4c72 scheme_default elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"f7a4c72\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c5b48a sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"8c5b48a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-348ecad animation_type_block sc_fly_static elementor-invisible elementor-widget elementor-widget-trx_sc_title\" data-id=\"348ecad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;healthhub-fadeinup&quot;}\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Testimonios<\/span><\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-510e276 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"510e276\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be34f3b sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"be34f3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Agradecemos a nuestros clientes que se tomen el tiempo de darnos su opini\u00f3n sobre nuestros servicios. Siempre nos gusta saber hasta qu\u00e9 punto estamos cumpliendo los objetivos y las expectativas de nuestros clientes y si estamos a la altura de los altos est\u00e1ndares que nos hemos marcado. <\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ac996c sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"8ac996c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63629ca sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"63629ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Todos estos testimonios est\u00e1n archivados en nuestra cl\u00ednica para su revisi\u00f3n. Algunos de los testimonios que aparecen a continuaci\u00f3n se han modificado para mayor claridad respecto a su versi\u00f3n original en espa\u00f1ol. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-507dd17 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"507dd17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-animation-type=\"sequental\" data-animation-stagger=\"\" data-mouse-helper=\"hover\" data-mouse-helper-hide-helper=\"1\" data-mouse-helper-centered=\"0\" data-mouse-helper-magnet=\"0\" data-mouse-helper-color=\"\" data-mouse-helper-bg-color=\"\" data-mouse-helper-bd-color=\"\" data-mouse-helper-bd-width=\"-1\" data-mouse-helper-mode=\"\" data-mouse-helper-axis=\"xy\" data-mouse-helper-delay=\"5\" data-mouse-helper-text=\"\" data-mouse-helper-text-size=\"\" data-mouse-helper-text-round=\"0\" data-mouse-helper-icon=\"\" data-mouse-helper-icon-size=\"\" data-mouse-helper-icon-color=\"\" data-mouse-helper-image=\"\" data-mouse-helper-layout=\"\" data-mouse-helper-class=\"\" data-mouse-helper-callback=\"\" data-mouse-helper-hide-cursor=\"0\" class=\"elementor-element elementor-element-c99833f animation_type_sequental sc_fly_static elementor-invisible elementor-widget elementor-widget-trx_sc_testimonials\" data-id=\"c99833f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;healthhub-fadeinup&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"trx_sc_testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div \t\tclass=\"sc_testimonials sc_testimonials_extra\"><div  class=\"sc_testimonials_slider sc_item_slider slider_swiper_outer slider_outer slider_outer_nocontrols slider_outer_pagination slider_outer_pagination_bullets slider_outer_pagination_pos_bottom slider_outer_nocentered slider_outer_overflow_hidden slider_outer_multi\">\n\t<div  data-slides-per-view-breakpoints=\"{&quot;999999&quot;:3}\" data-slides-space-breakpoints=\"{&quot;999999&quot;:6}\" class=\"slider_container swiper-slider-container slider_swiper slider_noresize slider_nocontrols slider_pagination slider_pagination_bullets slider_pagination_pos_bottom slider_nocentered slider_overflow_hidden slider_multi\" data-slides-per-view=\"3\" data-slides-space=\"6\" data-effect=\"slide\" data-slides-min-width=\"290\" data-pagination=\"bullets\" data-direction=\"horizontal\" data-mouse-wheel=\"0\" data-autoplay=\"0\" data-loop=\"1\" data-free-mode=\"0\" data-slides-centered=\"0\" data-slides-overflow=\"0\">\n\t\t<div class=\"slides slider-wrapper swiper-wrapper sc_item_columns_3\"><div class=\"slider-slide swiper-slide\"><div data-post-id=\"60589\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\">\n<p class=\"wp-block-paragraph\"><strong>Mioma uterino y s\u00edndrome de ovario poliqu\u00edstico (SOP)<\/strong> A los 23 a\u00f1os empec\u00e9 a tener mucho dolor en mis periodos menstruales, consult\u00e9 a mi ginec\u00f3logo y me diagnosticaron quistes ov\u00e1ricos y un fibroma en el \u00fatero; la recomendaci\u00f3n del m\u00e9dico fue la cirug\u00eda. Acud\u00ed a Pasaporte a la Salud con el Dr. Richard Smithee y \u00e9l elabor\u00f3 un plan de acupuntura para m\u00ed; tambi\u00e9n me orientaron hacia un cambio en los h\u00e1bitos alimenticios y el estilo de vida. Tras finalizar mi tratamiento\/programa en Pasaporte a la Salud, volv\u00ed a mi ginec\u00f3logo y descubrimos que todo mi sistema reproductivo estaba libre de quistes y que el fibroma hab\u00eda desaparecido. Por eso recomiendo Pasaporte a la Salud y estoy muy agradecida al Dr. Richard Smithee por su atenci\u00f3n amable y discreta.   <\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Claudia B.<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">Pacient<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"60590\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\">\n<p class=\"wp-block-paragraph\"><strong>C\u00e1ncer de pr\u00f3stata:<\/strong> Quiero compartir mi experiencia porque quiero que el p\u00fablico en general sepa que el C\u00c1NCER no es el fin de la vida. Soy acupuntor y, para m\u00ed, fue una llamada de atenci\u00f3n para cuidarme mejor. Tras una infecci\u00f3n urinaria me diagnosticaron c\u00e1ncer de pr\u00f3stata. Mis opciones, seg\u00fan mi m\u00e9dico y mi cirujano, eran las siguientes: 1) Cirug\u00eda de pr\u00f3stata, que inclu\u00eda la extirpaci\u00f3n de los ganglios linf\u00e1ticos y del tejido alrededor de la pr\u00f3stata. 2) Radiaci\u00f3n o quimioterapia para asegurarse de que el c\u00e1ncer se hubiera eliminado. 3) Medicaci\u00f3n en forma de pastillas para ayudar con los efectos secundarios de la cirug\u00eda, la quimio y\/o la radiaci\u00f3n. Me dijeron ENF\u00c1TICA y CONTUNDENTEMENTE que ten\u00eda que hacerme este procedimiento lo antes posible porque el c\u00e1ncer es una enfermedad mortal y hay que atacarlo de inmediato y el c\u00e1ncer no se puede curar. Por supuesto, despu\u00e9s de todo esto no hab\u00eda garant\u00edas de que yo fuera a estar libre de c\u00e1ncer. Practico la Medicina Oriental, as\u00ed que s\u00e9 por experiencia personal, y por la de mis pacientes, que nuestros cuerpos son capaces de sanarse de forma natural cuando les ayudamos y les damos una oportunidad. Por suerte para m\u00ed, un par de semanas antes hab\u00eda conocido a Richard Smithee, un acupuntor en Guaymas, as\u00ed que cuando me dieron la MALA noticia llam\u00e9 a Richard para pedir cita. Cuando me pregunt\u00f3: \u201c\u00bfC\u00f3mo puedo ayudarle?\u201d Le dije: \u201cNecesito un milagro\u201d y le entregu\u00e9 el papel con el diagn\u00f3stico; lo ley\u00f3 y dijo: \u201cPerm\u00edtame compartirle algo: todo el mundo tiene c\u00e9lulas cancerosas en su cuerpo, incluso los beb\u00e9s; la diferencia entre un c\u00e1ncer activo y un c\u00e1ncer inactivo la determina la fortaleza de nuestro sistema inmunitario. \u00a1Yo no curo el c\u00e1ncer! Pero, fortaleciendo el sistema inmunitario y desintoxicando el cuerpo y modificando las elecciones de estilo de vida, podemos nutrir el cuerpo para que se sane a s\u00ed mismo\u201d. Ese d\u00eda iniciamos el proceso de sanaci\u00f3n, segu\u00ed el protocolo que Richard me prescribi\u00f3 y ahora estoy LIBRE DE C\u00c1NCER. Ha sido una experiencia humilde, f\u00e1cil e interesante para m\u00ed porque, al ser un profesional de la salud, me hab\u00eda estado cuidando. Estaba seguro de que no me crecer\u00edan cosas como el c\u00e1ncer en el cuerpo, pero ocurri\u00f3, y soy una persona m\u00e1s sabia y m\u00e1s sana gracias a ello. Seg\u00fan mi experiencia con el C\u00c1NCER, es una forma suave y eficaz de abordar el c\u00e1ncer tratando los problemas de ra\u00edz que lo causaron.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Juan T.<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">Pacient<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"60592\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\">\n<p class=\"wp-block-paragraph\"><strong>Migra\u00f1as:<\/strong> Quiero tomarme un momento para expresar mi agradecimiento a Richard Smithee y por la ayuda m\u00e9dica que me ha brindado. Cuando conoc\u00ed a Richard por primera vez, pudo ver de inmediato, incluso sin preguntarme, que estaba sufriendo a nivel m\u00e9dico. Cuando me pregunt\u00f3 c\u00f3mo me sent\u00eda, percib\u00ed que realmente le importaba y que no lo preguntaba solo por cortes\u00eda. Le expliqu\u00e9 las migra\u00f1as que llevaba sufriendo desde ni\u00f1a y enseguida me dijo que pod\u00eda ayudarme. Recientemente me hab\u00edan hospitalizado de urgencia por una migra\u00f1a. El tratamiento fue ineficaz. Durante los \u00faltimos 5 meses de tratamiento con Richard, ha resuelto mis problemas de migra\u00f1a con acupuntura, terapia de masaje profundo y una nutrici\u00f3n adecuada. Su enfoque pr\u00e1ctico e integral de todo el cuerpo en la medicina ha supuesto una gran diferencia en mi vida. Richard se toma el tiempo de hacer muchas preguntas para ayudarle a determinar el enfoque correcto para la sanaci\u00f3n. Siempre se toma el tiempo de explicar los motivos de sus preguntas y c\u00f3mo el cuerpo est\u00e1 conectado. Su genuina preocupaci\u00f3n por las personas es muy evidente. Me siento muy segura de la capacidad de Richard para ayudar a las personas. He sugerido sus servicios a varias personas y seguir\u00e9 recomend\u00e1ndolo. Para m\u00ed, Richard siempre ser\u00e1 mi sanador y maestro. Cualquiera que acuda a \u00e9l en busca de ayuda m\u00e9dica recibir\u00e1 un enorme conocimiento m\u00e9dico, experiencia y una atenci\u00f3n genuina.<\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Colleen K.<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">Pacient<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"60593\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\">\n<p class=\"wp-block-paragraph\"><strong>Trastorno Bipolar (Trastorno Man\u00edaco-Depresivo):<\/strong>  Cuando ten\u00eda 14 a\u00f1os me diagnosticaron trastorno bipolar y me pusieron bajo cuidado m\u00e9dico-psiqui\u00e1trico durante un a\u00f1o sufriendo una fuerte depresi\u00f3n. Tambi\u00e9n hab\u00eda estado tomando remedios naturales que me hab\u00eda dado mi abuela, junto con otras personas que entend\u00edan de \u00abhierbas o medicina popular\u00bb, muchos remedios y quiz\u00e1s un poco de alivio, pero no lo que estaba buscando. Le\u00ed en internet que la medicina china tiene un efecto muy fuerte sobre la depresi\u00f3n, la ansiedad y para personas con problemas de drogas. Ped\u00ed cita con Richard Smithee en la cl\u00ednica Pasaporte a la Salud, una cl\u00ednica de medicina oriental. Despu\u00e9s de algunas explicaciones, que en ese momento no entend\u00ed por mi estado mental, recib\u00ed mi tratamiento, fue como si volviera a la vida, despu\u00e9s de muchos a\u00f1os de tristeza sin ninguna raz\u00f3n, y depresi\u00f3n sin saber por qu\u00e9, con miedo a todo. A veces con miedo de salir por la puerta de mi casa. Pude restablecer mis actividades diarias, pude volver a la escuela, y pude recuperar mi lucidez y mi felicidad, pude volver a disfrutar de la vida. Actualmente soy vendedor, estoy casado y tengo una hija, puedo sentir felicidad gracias al tratamiento que encontr\u00e9 aqu\u00ed en Pasaporte a la Salud, y recomiendo encarecidamente la medicina oriental y la experiencia es algo que valoro enormemente. \u00a1\u00a1\u00a1Ah!!! Un comentario que olvid\u00e9 en mi relato, mi recuperaci\u00f3n fue del 80 % en solo 15 d\u00edas, el resto fue mejorando paso a paso, este trastorno era cr\u00f3nico, pero en 15 d\u00edas recuper\u00e9 el amor por la vida&#8230; una vida llena de gracia.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Francisco Javier Ru\u00edz O.<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">Pacient<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"60595\" class=\"sc_testimonials_item sc_item_container post_container\">\n\t<div class=\"sc_testimonials_item_content\">\n<p class=\"wp-block-paragraph\"><strong>Dolor \u2013 zona lumbar\/piernas, dedos\/manos\/mu\u00f1ecas (en espera de cirug\u00eda):<\/strong> Le escribo esto a las 8:00 a. m. del domingo por la ma\u00f1ana, porque no puedo esperar a cont\u00e1rselo el mi\u00e9rcoles. Anoche, despu\u00e9s de mi 5.\u00ba tratamiento, pude mover mi pierna izquierda hacia arriba para apoyarla por encima de mi rodilla derecha. Rec\u00e9. No hab\u00eda podido hacer esto en m\u00e1s de 5 meses. Esta ma\u00f1ana pude hacer ejercicios de estiramiento sin dolor. Luego, cuando levant\u00e9 la pierna izquierda para apoyarla sobre mi rodilla derecha y atarme el zapato, me sent\u00ed euf\u00f3rica. Antes ni siquiera pod\u00eda forzarlo, porque el dolor era tan intenso. El dolor en las manos fue la raz\u00f3n por la que acud\u00ed a Passport To Health. Cuando mis m\u00e9dicos me dijeron que tendr\u00eda que someterme a cirug\u00edas dobles en ambas manos y mu\u00f1ecas, supe que ten\u00eda que probar opciones de medicina alternativa. Durante 2 a\u00f1os no he podido estar de pie en el fregadero y terminar de fregar los platos sin parar y sentarme a descansar. En los \u00faltimos dos d\u00edas he completado esta tarea sin parar, sin dolor de espalda ni de piernas, y con solo 2 semanas de 4 tratamientos. Ahora ya sabe por qu\u00e9 ten\u00eda que escribirle. El cuidado y la delicadeza que brinda a las personas demuestran que est\u00e1 utilizando sus conocimientos y el uso de este don otorgado por Dios. Espero que esta carta baste hasta que pueda darle las gracias en persona. Atentamente,               <\/p>\n<\/div>\n\t<div class=\"sc_testimonials_item_author\">\n\t\t\t\t<div class=\"sc_testimonials_item_author_data\">\n\t\t\t<h4 class=\"sc_testimonials_item_author_title\">Eleanor J.<\/h4>\n\t\t\t<div class=\"sc_testimonials_item_author_subtitle\">Pacient<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"slider_pagination_wrap swiper-pagination\"><\/div><\/div><\/div><!-- \/.sc_testimonials -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73f6f1d sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"73f6f1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0664ae2 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"0664ae2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d914900 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"d914900\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3dfb56 sc_fly_static elementor-widget elementor-widget-video\" data-id=\"b3dfb56\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-11-13-at-10.57.24-PM-1.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d173e8e sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"d173e8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bcf5e7 sc_fly_static elementor-widget elementor-widget-video\" data-id=\"3bcf5e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-11-13-at-10.57.23-PM-3-1.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-bfb0418 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"bfb0418\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6baebd sc_fly_static elementor-widget elementor-widget-video\" data-id=\"e6baebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-11-13-at-10.57.23-PM-2-1.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7fb9c5d sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7fb9c5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21d031a sc_fly_static elementor-widget elementor-widget-video\" data-id=\"21d031a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-11-13-at-10.57.23-PM-1-1.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf112fd elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"bf112fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d3d183 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"8d3d183\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-450685c sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"450685c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fff45c sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"5fff45c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc147a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"fc147a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a63efbc sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a63efbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26cbf02 sc_fly_static elementor-widget elementor-widget-video\" data-id=\"26cbf02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-11-13-at-10.57.22-PM-1-1.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-85111f7 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"85111f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a817e2 sc_fly_static elementor-widget elementor-widget-video\" data-id=\"0a817e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-11-13-at-10.57.23-PM-4.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-645839d sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"645839d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2089d83 sc_fly_static elementor-widget elementor-widget-video\" data-id=\"2089d83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-11-13-at-10.57.22-PM-1-1-1.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7f4a5b2 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7f4a5b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c901ed elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"2c901ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0075928 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"0075928\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff4868a sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"ff4868a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25ed96e elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"25ed96e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5757878 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"5757878\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db67eea sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"db67eea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Testimonios Agradecemos a nuestros clientes que se tomen el tiempo de darnos su opini\u00f3n sobre nuestros servicios. Siempre nos gusta saber hasta qu\u00e9 punto estamos cumpliendo los objetivos y las&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-60553","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Testimonios de Pacientes | Pasaporte Salud<\/title>\n<meta name=\"description\" content=\"Lea testimonios reales de pacientes de M\u00e9xico, EE. UU. y Canad\u00e1 que mejoraron su salud con acupuntura y medicina oriental en nuestra cl\u00ednica de Guaymas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pasaportealasalud.com\/es\/testimonios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Testimonios de Pacientes | Pasaporte Salud\" \/>\n<meta property=\"og:description\" content=\"Lea testimonios reales de pacientes de M\u00e9xico, EE. UU. y Canad\u00e1 que mejoraron su salud con acupuntura y medicina oriental en nuestra cl\u00ednica de Guaymas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pasaportealasalud.com\/es\/testimonios\/\" \/>\n<meta property=\"og:site_name\" content=\"Pasaporte\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T12:55:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2025-11-22-at-6.23.25-AM-1-120x120.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Testimonios de Pacientes | Pasaporte Salud","description":"Lea testimonios reales de pacientes de M\u00e9xico, EE. UU. y Canad\u00e1 que mejoraron su salud con acupuntura y medicina oriental en nuestra cl\u00ednica de Guaymas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pasaportealasalud.com\/es\/testimonios\/","og_locale":"es_ES","og_type":"article","og_title":"Testimonios de Pacientes | Pasaporte Salud","og_description":"Lea testimonios reales de pacientes de M\u00e9xico, EE. UU. y Canad\u00e1 que mejoraron su salud con acupuntura y medicina oriental en nuestra cl\u00ednica de Guaymas.","og_url":"https:\/\/pasaportealasalud.com\/es\/testimonios\/","og_site_name":"Pasaporte","article_modified_time":"2026-07-23T12:55:32+00:00","og_image":[{"url":"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2025-11-22-at-6.23.25-AM-1-120x120.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pasaportealasalud.com\/es\/testimonios\/","url":"https:\/\/pasaportealasalud.com\/es\/testimonios\/","name":"Testimonios de Pacientes | Pasaporte Salud","isPartOf":{"@id":"https:\/\/pasaportealasalud.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pasaportealasalud.com\/es\/testimonios\/#primaryimage"},"image":{"@id":"https:\/\/pasaportealasalud.com\/es\/testimonios\/#primaryimage"},"thumbnailUrl":"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2025-11-22-at-6.23.25-AM-1-120x120.webp","datePublished":"2025-11-24T10:42:39+00:00","dateModified":"2026-07-23T12:55:32+00:00","description":"Lea testimonios reales de pacientes de M\u00e9xico, EE. UU. y Canad\u00e1 que mejoraron su salud con acupuntura y medicina oriental en nuestra cl\u00ednica de Guaymas.","breadcrumb":{"@id":"https:\/\/pasaportealasalud.com\/es\/testimonios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pasaportealasalud.com\/es\/testimonios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pasaportealasalud.com\/es\/testimonios\/#primaryimage","url":"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2025-11-22-at-6.23.25-AM-1-120x120.webp","contentUrl":"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2025-11-22-at-6.23.25-AM-1-120x120.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/pasaportealasalud.com\/es\/testimonios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pasaportealasalud.com\/es\/"},{"@type":"ListItem","position":2,"name":"Testimonios"}]},{"@type":"WebSite","@id":"https:\/\/pasaportealasalud.com\/es\/#website","url":"https:\/\/pasaportealasalud.com\/es\/","name":"Pasaporte","description":"Pasaporte a la salud | Cl\u00ednica de auto cuidado personal | Guaymas Sonora","publisher":{"@id":"https:\/\/pasaportealasalud.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pasaportealasalud.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pasaportealasalud.com\/es\/#organization","name":"Pasaporte","url":"https:\/\/pasaportealasalud.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pasaportealasalud.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-26-at-11.18.36-PM.webp","contentUrl":"https:\/\/pasaportealasalud.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-26-at-11.18.36-PM.webp","width":1218,"height":376,"caption":"Pasaporte"},"image":{"@id":"https:\/\/pasaportealasalud.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pasaportealasalud.com\/es\/wp-json\/wp\/v2\/pages\/60553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pasaportealasalud.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pasaportealasalud.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pasaportealasalud.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pasaportealasalud.com\/es\/wp-json\/wp\/v2\/comments?post=60553"}],"version-history":[{"count":0,"href":"https:\/\/pasaportealasalud.com\/es\/wp-json\/wp\/v2\/pages\/60553\/revisions"}],"wp:attachment":[{"href":"https:\/\/pasaportealasalud.com\/es\/wp-json\/wp\/v2\/media?parent=60553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}